{"id":89,"date":"2011-05-01T12:33:42","date_gmt":"2011-05-01T12:33:42","guid":{"rendered":"http:\/\/pre.sourtech.com\/sourtech\/blog\/?p=89"},"modified":"2017-01-16T13:49:29","modified_gmt":"2017-01-16T13:49:29","slug":"el-mundo-groundswell-bibliografia-basica-de-un-community-manager","status":"publish","type":"post","link":"https:\/\/www.sourtech.com\/blog\/libros\/el-mundo-groundswell-bibliografia-basica-de-un-community-manager\/","title":{"rendered":"El Mundo Groundswell bibliograf\u00eda b\u00e1sica de un Community Manager"},"content":{"rendered":"<p>El <a title=\"Ficha del libro el mundo groundswell\" href=\"http:\/\/empresactiva.blogspot.com\/2009\/03\/el-mundo-groundswell-josh-bernoff.html\" target=\"_blank\">Mundo Groundswell<\/a> es uno de los grandes libros de empresa, comunicaci\u00f3n y 2.0 que todo el mundo deber\u00eda tener en su biblioteca pero si ere un CM o quieres serlo es uno de los imprescindible que lo leas antes de nada ya que en 380 p\u00e1ginas adquieres una visi\u00f3n muy completa del trabajo que debe desempe\u00f1ar un CM pero sobre todo de la cantidad de informaci\u00f3n que debe controlar y gestionar.<\/p>\n<p>El problema que ha habido con la profesi\u00f3n de Community Manager es que muchas personas se han puesto la etiqueta en su tarjeta de visita pero intuyendo que era un trench y habia que seguirlo, pero la realidad es que ser Community va m\u00e1s all\u00e1 de escribir un post en Facebook y mandar unos tweets. Hay que analizar y profundizar para gestionar una comunidad (clientes-personas) y lograr los fines (objetivos-ventas-fidelizacion-imagen de marca) pero como ni las comunidades son todas iguales, ni los fines son \u00fanicos y por ello hay que saber muy bien donde nos metemos y justamente este libro nos dar\u00e1 una clara visi\u00f3n.<\/p>\n<div id=\"attachment_90\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-90\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-90\" alt=\"Portada Libro El mundo Groundswell\" src=\"http:\/\/pre.sourtech.com\/sourtech\/blog\/wp-content\/uploads\/2013\/10\/el-mundo-groundswell.jpg\" width=\"400\" height=\"632\" srcset=\"https:\/\/www.sourtech.com\/blog\/wp-content\/uploads\/2013\/10\/el-mundo-groundswell.jpg 400w, https:\/\/www.sourtech.com\/blog\/wp-content\/uploads\/2013\/10\/el-mundo-groundswell-189x300.jpg 189w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><p id=\"caption-attachment-90\" class=\"wp-caption-text\">Portada Libro El mundo Groundswell<\/p><\/div>\n<p>Para entender hasta que punto este libro puede ser un b\u00e1sico en la Bibliograf\u00eda de todo Community Manager el presidente de <a title=\"Asociaci\u00f3n Espa\u00f1ola de Responsables de Comunidades OnLine\" href=\"http:\/\/www.aercomunidad.org\/\" target=\"_blank\">AERCO<\/a> Asociaci\u00f3n Espa\u00f1ola de Responsable de Comunidad Online, Jos\u00e9 Antonio Gallego, no paro hasta lograr montar un evento con la presencia de uno de los autores, aprovechando la traducci\u00f3n de la obra al castellano. Os dejo la <a title=\"Comunidad en Red\" href=\"http:\/\/www.comunidadenlared.com\/2009\/06\/02\/presentacion-en-madrid-de-el-mundo-groundswell-por-josh-bernoff\/\" target=\"_blank\">entrada de su blog<\/a> hablando sobre el tema.<\/p>\n<p><strong>Bibliograf\u00eda b\u00e1sica<\/strong> Por\u00a0 bibliograf\u00eda b\u00e1sica entendemos en <a title=\"Pagina oficinal de Sourtech\" href=\"http:\/\/www.sourtech.com\/\" target=\"_blank\">Sourtech<\/a> que son las obras que nos\u00a0 hemos le\u00eddo o debemos leernos que deber\u00edan estar en toda biblioteca\u00a0 profesional y personal. Son esos libros que por alg\u00fan motivo destacan y\u00a0 logran aportar claridad y visi\u00f3n a nuestro entorno profesional, muchas\u00a0 veces no nos dicen nada nuevo sino que recolocan los objetos mentales en\u00a0 su orden natural y nos dan una visi\u00f3n completa de nuestros propios\u00a0 conocimientos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Mundo Groundswell es uno de los grandes libros de empresa, comunicaci\u00f3n y 2.0 que todo el mundo deber\u00eda tener en su biblioteca pero si ere un CM o quieres serlo es uno de los imprescindible que lo leas antes de nada ya que en 380 p\u00e1ginas adquieres una visi\u00f3n muy completa del trabajo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[13,46,12],"_links":{"self":[{"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/posts\/89"}],"collection":[{"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":1,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"predecessor-version":[{"id":91,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/posts\/89\/revisions\/91"}],"wp:attachment":[{"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sourtech.com\/blog\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}